{"id":117,"count":5,"description":"","link":"http:\/\/www.sotm-audio.com\/sotmwp\/english\/product-category\/source\/network-player\/","name":"Network player","slug":"network-player","taxonomy":"product_cat","parent":115,"meta":[],"menu_order":0,"_links":{"self":[{"href":"http:\/\/www.sotm-audio.com\/sotmwp\/english\/wp-json\/wp\/v2\/product_cat\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.sotm-audio.com\/sotmwp\/english\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"http:\/\/www.sotm-audio.com\/sotmwp\/english\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"http:\/\/www.sotm-audio.com\/sotmwp\/english\/wp-json\/wp\/v2\/product_cat\/115"}],"wp:post_type":[{"href":"http:\/\/www.sotm-audio.com\/sotmwp\/english\/wp-json\/wp\/v2\/product?product_cat=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}